{"id":38799,"date":"2024-02-13T23:55:00","date_gmt":"2024-02-13T22:55:00","guid":{"rendered":"https:\/\/lamagicbox.com\/magazine\/?p=38799"},"modified":"2024-02-25T20:53:43","modified_gmt":"2024-02-25T19:53:43","slug":"chat-tomalo-et-zantek-le-noktambul-rennes","status":"publish","type":"post","link":"https:\/\/lamagicbox.com\/magazine\/chat-tomalo-et-zantek-le-noktambul-rennes\/","title":{"rendered":"Chat Tomalo + Zantek &#8211; Le Noktambul &#8211; Rennes (35)"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-38799\" data-postid=\"38799\" class=\"themify_builder_content themify_builder_content-38799 themify_builder tf_clear\">\n    \t\t\t\t<!-- module_row -->\n\t\t<div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_455u398 tb_first tf_w tf_clearfix\">\n\t\t\t\t\t<div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n\t\t\t\t\t<div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_fa4z399 first\">\n\t\t\t\t\t\t\t\t\t<div class=\"tb-column-inner tf_box tf_w\">\n\t\t\t\t<!-- module text -->\n<div  class=\"module module-text tb_8x2e962   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n    <h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-38820\" title=\"chat-tomalo-2024-02-03-950\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950.jpg\" alt=\"Chat Tomalo et Zantek au Noktamb\u00fcl \u00e0 Rennes\" width=\"950\" height=\"300\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950.jpg 950w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950-300x95.jpg 300w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950-500x158.jpg 500w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/h2>\n<h1><strong><span style=\"color: #800000;\">CHAT TOMALO <span style=\"color: #000000;\">\/<\/span> ZANTEK<\/span>\u00a0en concert<\/strong><\/h1>\n<p><strong><i>Quand deux galaxies musicales se t\u00e9lescopent et s&rsquo;unissent&#8230;<\/i><\/strong><\/p>\n<h4><em><strong>Date :<\/strong><\/em> 13 f\u00e9vrier 2024<br \/><em><strong>Salle :<\/strong><\/em> Le Noktamb\u00fcl<br \/><strong><em>Lieu :<\/em><\/strong> Bretagne, Rennes\u00a0(35)<\/h4>\n<p style=\"text-align: right;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<hr \/>\n<p style=\"text-align: right;\"><em>Par\u00a0<strong>Mike S.<br \/><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><i><b>C&rsquo;est dans cette salle qui s&rsquo;appelait encore le Mondo Bizarro il y a peu que nous avons rendez-vous ce soir pour d\u00e9couvrir sur sc\u00e8ne une double affiche, Chat Tomalo et Zantek. Aujourd&rsquo;hui rebaptis\u00e9e le Noktamb\u00fcl, cette salle garde encore quelques stigmates de sa vie d&rsquo;avant. La programmation de ce soir, entre pop, folk et rock fran\u00e7ais, va faire \u00e0 nouveau vibrer ses murs.<\/b><\/i><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est avec le rock de <strong>Zantek<\/strong> que la soir\u00e9e d\u00e9bute. Si les guitares sont folk, \u00e9lectro-acoustique, le son, lui, est bien rock, et en fran\u00e7ais dans le texte. Alex Zantek, seul sur sc\u00e8ne, avec pour seule compagnie, ses trois guitares, deux folk et une \u00e9lectrique. Le chanteur nous pr\u00e9sente quelques uns des titres les plus embl\u00e9matiques de son r\u00e9pertoire que l&rsquo;on aimerait voir un jour r\u00e9uni sur un long format, bien en vue, au rayon Rock fran\u00e7ais des meilleurs disquaires.<\/p>\n<p style=\"text-align: justify;\">Car Zantek n&rsquo;a pas encore de v\u00e9ritable album \u00e0 son actif, juste quelques ep&rsquo;s introuvables, sortis en 2017 et 2020. Pourtant, les titres qu&rsquo;il propose ce soir ont tous une identit\u00e9 particuli\u00e8re, comme <a href=\"https:\/\/youtu.be\/gHOXv1HApJ8\" target=\"_blank\" rel=\"noopener\"><em>Anorak<\/em><\/a>, <em>Sur la plage bond\u00e9e (<\/em><a href=\"https:\/\/youtu.be\/u-sLQD1teP0\" target=\"_blank\" rel=\"noopener\">clip\u00e9 l&rsquo;\u00e9t\u00e9 dernier<\/a>), <em>L&rsquo;\u00e9t\u00e9 n&rsquo;en finit pas.\u00a0<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38801 aligncenter\" title=\"zantek-2024-02-01-500\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500.jpg\" alt=\"Zantek en concert au Noktamb\u00fcl\" width=\"500\" height=\"333\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500.jpg 500w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500-225x150.jpg 225w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500-450x300.jpg 450w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Il y a aussi un petit rat\u00e9 autour du titre <em>Impr\u00e9vu<\/em>, le bien nomm\u00e9, sur lequel il ne reviendra pas, m\u00eame en rappel. Il lui pr\u00e9f\u00e8rera un tout nouveau morceau, dont le titre reste encore incertain (sans doute : <em>Tourne tourne, tourne<\/em>) et\u00a0 qui, d\u00e9j\u00e0, a tout d&rsquo;un tube.<\/p>\n<p style=\"text-align: justify;\">Tout au long de ce set de 45 mn, le son est \u00e2pre, la voix est grave. Les guitares folk ou \u00e9lectro-folk sont utilis\u00e9es \u00e0 contre-emploi, ici, les cordes \u00e9tant malmen\u00e9es, comme si elles \u00e9taient en acier pos\u00e9es sur une guitare \u00e9lectrique. L&rsquo;Epiphone \u00e9lectrique, une semi hollow aux couleurs vintage, restera durant tout le set inlassablement immobile dans le dos du chanteur.\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">En r\u00e9alit\u00e9, elle ne s&rsquo;animera qu&rsquo;\u00e0 partir du second set, avec l&rsquo;arriv\u00e9e du rennais d&rsquo;adoption <strong>Chat Tomalo<\/strong> et de sa pop folk pleine d&rsquo;\u00e9l\u00e9gance. Car, pour cette seconde partie de soir\u00e9e, le changement de plateau n&rsquo;est pas total. Pour ceux qui ont d\u00e9j\u00e0 vu Chat Tomalo sur sc\u00e8ne, ces derniers mois, la formation solo de Philippe au chant et \u00e0 la guitare, a \u00e9t\u00e9 renforc\u00e9e par la guitare \u00e9lectrique de d&rsquo;<strong>Alex Zantek<\/strong>. On y retrouve alors beaucoup de titres entendus auparavant (<em>Sing, Pop, Lack&#8230;<\/em>), mais avec un son enrichi, plus volumineux, plus nerveux aussi, et plus intense, mais sans rien retirer \u00e0 son \u00e9l\u00e9gance originelle.\u00a0 \u00a0\u00a0<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-38802\" title=\"chat-tomalo-2024-02-01-500\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500.jpg\" alt=\"Chat Tomalo en concert\" width=\"500\" height=\"375\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500.jpg 500w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500-200x150.jpg 200w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500-400x300.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: justify;\">Cette transformation en duo est aussi l&rsquo;occasion pour le chanteur de se lib\u00e9rer un instant de sa propre guitare et de s&rsquo;approcher du public, micro \u00e0 la m\u00eame. Un public bien trop rare, il faut bien l&rsquo;admettre, mais totalement conquis par les m\u00e9lodies impeccables et les refrains ensorcelants. Les deux musiciens nous proposent en guise de rappel, une nouveaut\u00e9 aussi, <em>A Day<\/em>, un titre tout nouveau, encore jamais jou\u00e9 sur sc\u00e8ne, mais qui vient se fondre parfaitement dans le r\u00e9pertoire de l&rsquo;artiste.\u00a0<\/p>\n<p style=\"text-align: justify;\">Comme pour Zantek, en d\u00e9but de soir\u00e9e, on attend maintenant l&rsquo;arriv\u00e9e d&rsquo;un disque. Pour Chat Tomalo, ce serait une premi\u00e8re ! Et pourquoi pas, comme ils ont pu l&rsquo;\u00e9voquer apr\u00e8s le concert, un split CD (ou vinyle) ? Une id\u00e9e \u00e0 garder dans un coin de la t\u00eate, histoire d&rsquo;aller au bout du t\u00e9lescopage de ces deux galaxies musicales&#8230; En tout cas, vu la qualit\u00e9 des deux concerts, ce qu&rsquo;on pourrait y retrouver sur disque, ne pourra qu&rsquo;\u00eatre de bonne facture. On est impatient !\u00a0<\/p>\n<p><strong>Setlist Chat Tomalo :<\/strong> Lack &#8211; Over me &#8211; Pink &#8211; Ho my &#8211; Sing &#8211; N.O. &#8211; Fire &#8211; Pop &#8211; Floating &#8211; <strong><em>rappel :<\/em><\/strong> A day<\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><em>Merci aux musiciens, aux techniciens et aux organisateurs de cette belle soir\u00e9e au Noktamb\u00fcl !<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-38814\" title=\"chat-tomalo-2024-02-10-500\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500.jpg 500w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500-200x150.jpg 200w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500-400x300.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<hr \/>\n<p><strong><em>Zantek<\/em><\/strong> : <a href=\"https:\/\/www.zantek.fr\/\" target=\"_blank\" rel=\"noopener\">Site<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.facebook.com\/zantekmusic\" target=\"_blank\" rel=\"noopener\">FB<\/a><\/p>\n<p><strong><em>Chat Tomalo<\/em><\/strong> : <a href=\"https:\/\/www.facebook.com\/chattomalo\" target=\"_blank\" rel=\"noopener\">FB<\/a><\/p>\n<p><strong class=\"truncate_more\">[hr color=\u00a0\u00bbred\u00a0\u00bb]<\/strong><\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->\t\t\t\t<\/div><!-- .tb-column-inner -->\n\t\t\t\t\t\t<\/div><!-- .module_column -->\n\t\t\t\t\t\t<\/div><!-- .row_inner -->\n\t\t<\/div><!-- .module_row -->\n\t\t\t\t<\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>CHAT TOMALO \/ ZANTEK\u00a0en concert Quand deux galaxies musicales se t\u00e9lescopent et s&rsquo;unissent&#8230; Date : 13 f\u00e9vrier 2024Salle : Le Noktamb\u00fclLieu : Bretagne, Rennes\u00a0(35) . Par\u00a0Mike S. C&rsquo;est dans cette salle qui s&rsquo;appelait encore le Mondo Bizarro il y a peu que nous avons rendez-vous ce soir pour d\u00e9couvrir sur sc\u00e8ne une double affiche, Chat [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[1124,4070,1553,50,605,1914,765,4071],"class_list":["post-38799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reportage-concert","tag-bretagne","tag-chat-tomalo","tag-folk","tag-pop","tag-rennes","tag-rock-francais","tag-saint-malo","tag-zantek","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<h2><img loading=\"lazy\" decoding=\"async\" title=\"chat-tomalo-2024-02-03-950\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950.jpg\" alt=\"Chat Tomalo et Zantek au Noktamb\u00fcl \u00e0 Rennes\" width=\"950\" height=\"300\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950.jpg 950w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950-300x95.jpg 300w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-03-950-500x158.jpg 500w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/h2> <h1><strong>CHAT TOMALO \/ ZANTEK\u00a0en concert<\/strong><\/h1> <p><strong><i>Quand deux galaxies musicales se t\u00e9lescopent et s'unissent...<\/i><\/strong><\/p> <h4><em><strong>Date :<\/strong><\/em> 13 f\u00e9vrier 2024<br \/><em><strong>Salle :<\/strong><\/em> Le Noktamb\u00fcl<br \/><strong><em>Lieu :<\/em><\/strong> Bretagne, Rennes\u00a0(35)<\/h4> <p style=\"text-align: right;\">.<\/p> <hr \/> <p style=\"text-align: right;\"><em>Par\u00a0<strong>Mike S.<br \/><\/strong><\/em><\/p> <p style=\"text-align: justify;\"><i><b>C'est dans cette salle qui s'appelait encore le Mondo Bizarro il y a peu que nous avons rendez-vous ce soir pour d\u00e9couvrir sur sc\u00e8ne une double affiche, Chat Tomalo et Zantek. Aujourd'hui rebaptis\u00e9e le Noktamb\u00fcl, cette salle garde encore quelques stigmates de sa vie d'avant. La programmation de ce soir, entre pop, folk et rock fran\u00e7ais, va faire \u00e0 nouveau vibrer ses murs.<\/b><\/i><\/p> <p style=\"text-align: justify;\">C'est avec le rock de <strong>Zantek<\/strong> que la soir\u00e9e d\u00e9bute. Si les guitares sont folk, \u00e9lectro-acoustique, le son, lui, est bien rock, et en fran\u00e7ais dans le texte. Alex Zantek, seul sur sc\u00e8ne, avec pour seule compagnie, ses trois guitares, deux folk et une \u00e9lectrique. Le chanteur nous pr\u00e9sente quelques uns des titres les plus embl\u00e9matiques de son r\u00e9pertoire que l'on aimerait voir un jour r\u00e9uni sur un long format, bien en vue, au rayon Rock fran\u00e7ais des meilleurs disquaires.<\/p> <p style=\"text-align: justify;\">Car Zantek n'a pas encore de v\u00e9ritable album \u00e0 son actif, juste quelques ep's introuvables, sortis en 2017 et 2020. Pourtant, les titres qu'il propose ce soir ont tous une identit\u00e9 particuli\u00e8re, comme <a href=\"https:\/\/youtu.be\/gHOXv1HApJ8\" target=\"_blank\" rel=\"noopener\"><em>Anorak<\/em><\/a>, <em>Sur la plage bond\u00e9e (<\/em><a href=\"https:\/\/youtu.be\/u-sLQD1teP0\" target=\"_blank\" rel=\"noopener\">clip\u00e9 l'\u00e9t\u00e9 dernier<\/a>), <em>L'\u00e9t\u00e9 n'en finit pas.\u00a0<\/em><\/p> <p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" title=\"zantek-2024-02-01-500\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500.jpg\" alt=\"Zantek en concert au Noktamb\u00fcl\" width=\"500\" height=\"333\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500.jpg 500w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500-225x150.jpg 225w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/zantek-2024-02-01-500-450x300.jpg 450w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p> <p>Il y a aussi un petit rat\u00e9 autour du titre <em>Impr\u00e9vu<\/em>, le bien nomm\u00e9, sur lequel il ne reviendra pas, m\u00eame en rappel. Il lui pr\u00e9f\u00e8rera un tout nouveau morceau, dont le titre reste encore incertain (sans doute : <em>Tourne tourne, tourne<\/em>) et\u00a0 qui, d\u00e9j\u00e0, a tout d'un tube.<\/p> <p style=\"text-align: justify;\">Tout au long de ce set de 45 mn, le son est \u00e2pre, la voix est grave. Les guitares folk ou \u00e9lectro-folk sont utilis\u00e9es \u00e0 contre-emploi, ici, les cordes \u00e9tant malmen\u00e9es, comme si elles \u00e9taient en acier pos\u00e9es sur une guitare \u00e9lectrique. L'Epiphone \u00e9lectrique, une semi hollow aux couleurs vintage, restera durant tout le set inlassablement immobile dans le dos du chanteur.\u00a0\u00a0<\/p> <p style=\"text-align: justify;\">En r\u00e9alit\u00e9, elle ne s'animera qu'\u00e0 partir du second set, avec l'arriv\u00e9e du rennais d'adoption <strong>Chat Tomalo<\/strong> et de sa pop folk pleine d'\u00e9l\u00e9gance. Car, pour cette seconde partie de soir\u00e9e, le changement de plateau n'est pas total. Pour ceux qui ont d\u00e9j\u00e0 vu Chat Tomalo sur sc\u00e8ne, ces derniers mois, la formation solo de Philippe au chant et \u00e0 la guitare, a \u00e9t\u00e9 renforc\u00e9e par la guitare \u00e9lectrique de d'<strong>Alex Zantek<\/strong>. On y retrouve alors beaucoup de titres entendus auparavant (<em>Sing, Pop, Lack...<\/em>), mais avec un son enrichi, plus volumineux, plus nerveux aussi, et plus intense, mais sans rien retirer \u00e0 son \u00e9l\u00e9gance originelle.\u00a0 \u00a0\u00a0<\/p> <p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" title=\"chat-tomalo-2024-02-01-500\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500.jpg\" alt=\"Chat Tomalo en concert\" width=\"500\" height=\"375\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500.jpg 500w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500-200x150.jpg 200w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-01-500-400x300.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p> <p style=\"text-align: justify;\">Cette transformation en duo est aussi l'occasion pour le chanteur de se lib\u00e9rer un instant de sa propre guitare et de s'approcher du public, micro \u00e0 la m\u00eame. Un public bien trop rare, il faut bien l'admettre, mais totalement conquis par les m\u00e9lodies impeccables et les refrains ensorcelants. Les deux musiciens nous proposent en guise de rappel, une nouveaut\u00e9 aussi, <em>A Day<\/em>, un titre tout nouveau, encore jamais jou\u00e9 sur sc\u00e8ne, mais qui vient se fondre parfaitement dans le r\u00e9pertoire de l'artiste.\u00a0<\/p> <p style=\"text-align: justify;\">Comme pour Zantek, en d\u00e9but de soir\u00e9e, on attend maintenant l'arriv\u00e9e d'un disque. Pour Chat Tomalo, ce serait une premi\u00e8re ! Et pourquoi pas, comme ils ont pu l'\u00e9voquer apr\u00e8s le concert, un split CD (ou vinyle) ? Une id\u00e9e \u00e0 garder dans un coin de la t\u00eate, histoire d'aller au bout du t\u00e9lescopage de ces deux galaxies musicales... En tout cas, vu la qualit\u00e9 des deux concerts, ce qu'on pourrait y retrouver sur disque, ne pourra qu'\u00eatre de bonne facture. On est impatient !\u00a0<\/p> <p><strong>Setlist Chat Tomalo :<\/strong> Lack - Over me - Pink - Ho my - Sing - N.O. - Fire - Pop - Floating - <strong><em>rappel :<\/em><\/strong> A day<\/p> <hr \/> <p style=\"text-align: justify;\"><em>Merci aux musiciens, aux techniciens et aux organisateurs de cette belle soir\u00e9e au Noktamb\u00fcl !<\/em><\/p> <p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" title=\"chat-tomalo-2024-02-10-500\" src=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500.jpg 500w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500-200x150.jpg 200w, https:\/\/lamagicbox.com\/magazine\/wp-content\/uploads\/2024\/02\/chat-tomalo-2024-02-10-500-400x300.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p> <hr \/> <p><strong><em>Zantek<\/em><\/strong> : <a href=\"https:\/\/www.zantek.fr\/\" target=\"_blank\" rel=\"noopener\">Site<\/a>\u00a0\/\u00a0<a href=\"https:\/\/www.facebook.com\/zantekmusic\" target=\"_blank\" rel=\"noopener\">FB<\/a><\/p> <p><strong><em>Chat Tomalo<\/em><\/strong> : <a href=\"https:\/\/www.facebook.com\/chattomalo\" target=\"_blank\" rel=\"noopener\">FB<\/a><\/p> <p><strong>[hr color=\"red\"]<\/strong><\/p> <p style=\"text-align: center;\">\u00a0<\/p>","_links":{"self":[{"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/posts\/38799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/comments?post=38799"}],"version-history":[{"count":28,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/posts\/38799\/revisions"}],"predecessor-version":[{"id":39502,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/posts\/38799\/revisions\/39502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/media\/38820"}],"wp:attachment":[{"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/media?parent=38799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/categories?post=38799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lamagicbox.com\/magazine\/wp-json\/wp\/v2\/tags?post=38799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}